{"id":2213,"date":"2022-08-18T22:51:59","date_gmt":"2022-08-18T22:51:59","guid":{"rendered":"https:\/\/centauritech.com\/?page_id=2213"},"modified":"2025-10-01T21:39:08","modified_gmt":"2025-10-01T21:39:08","slug":"consultoria-e-id","status":"publish","type":"page","link":"https:\/\/centauritech.com\/en\/consultoria-e-id\/","title":{"rendered":"Consultor\u00eda E I+D"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2213\" class=\"elementor elementor-2213\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bfade2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4bfade2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fba879a\" data-id=\"fba879a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5975973 elementor-widget elementor-widget-heading\" data-id=\"5975973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b70a0c elementor-align-left elementor-mobile-align-left elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"8b70a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/centauritech.com\/en\/demo-de-consultoria\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar Demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-843468c\" data-id=\"843468c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9edb197 elementor-reverse-mobile elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9edb197\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22cdc3f\" data-id=\"22cdc3f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e53edf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e53edf4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cb87f1d\" data-id=\"cb87f1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef9f454 elementor-widget elementor-widget-image\" data-id=\"ef9f454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2215\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-998a31a elementor-widget elementor-widget-heading\" data-id=\"998a31a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sobre nuestros servicios de Consultor\u00eda e I + D<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a770838 elementor-widget elementor-widget-spacer\" data-id=\"a770838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3280062 elementor-widget elementor-widget-text-editor\" data-id=\"3280062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mejor transformaci\u00f3n digital es deliberada y razonada, tomando decisiones de inversi\u00f3n y cambios con base en el contexto de la organizaci\u00f3n y las oportunidades que brinda el estado del arte. Sin embargo el contexto y el estado del arte cambian aceleradamente. Cuando su negocio permite el tiempo para irse posicionando tecnol\u00f3gicamente, una combinaci\u00f3n adecuada de consultor\u00eda, desarrollo de pruebas de concepto e investigaci\u00f3n si es necesario, contribuye a disminuir la incertidumbre sobre las decisiones que tomar.<\/p><p>En Centauri tenemos a\u00f1os acumulados solucionando problemas gerenciales y tecnol\u00f3gicos complejos o elaborando y ayudando a implementar estrategias de transformaci\u00f3n digital. Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo.<\/p><p>Nuestro historial de logros incluye transformaciones digitales completas de servicios o negocios, incluyendo conversi\u00f3n a transaccionalidad digital, digitalizaci\u00f3n de operaciones enteras, normativa de comercio electr\u00f3nico, an\u00e1lisis e interpretaci\u00f3n de cuerpos de datos para toma de decisiones, automatizaci\u00f3n de procesos de diagn\u00f3stico, pruebas de concepto de sistemas de informaci\u00f3n completos, diagn\u00f3sticos de fallas de sistemas y dise\u00f1o de arquitecturas avanzadas. Nuestro personal tiene a\u00f1os de experiencia en proyectos sofisticados de Investigaci\u00f3n y Desarrollo al igual que a\u00f1os de experiencia participando en Juntas Directivas, Comit\u00e9s Ejecutivos, Alta Gerencia y Gerencia de Negocios.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-06ef099 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"06ef099\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Comparte en: <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6f66d8 elementor-share-buttons--view-icon elementor-share-buttons--shape-circle elementor-share-buttons--color-custom elementor-widget__width-initial elementor-share-buttons--skin-gradient elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"e6f66d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-telegram\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2b2206\" data-id=\"f2b2206\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1356be elementor-widget elementor-widget-heading\" data-id=\"f1356be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Inf\u00f3rmate con Nosotros<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5bb605 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e5bb605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff0f113 elementor-cta--skin-cover elementor-hidden-mobile elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ff0f113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/Infografia.webp);\" role=\"img\" aria-label=\"Infografia\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tVISITA NUESTRO CTN\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tConoce las \u00faltimas noticias acerca de la ciberseguridad\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/centauritech.com\/en\/recursos-centauri\/\">\n\t\t\t\t\t\tIR AHORA\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-ribbon elementor-ribbon-right\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\t\u00a1Infograf\u00edas!\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d51f179 elementor-widget elementor-widget-spacer\" data-id=\"d51f179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e034ed2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"e034ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Conoce los casos de \u00e9xitos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01c76e2 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"01c76e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc8eb5 elementor-cta--skin-cover elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ebc8eb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/success-cases.jpeg);\" role=\"img\" aria-label=\"success cases\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tTestimonios de Clientes\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tConoce los cliente con qui\u00e9nes hemos trabajado, y algunas de las soluciones que hemos ofrecido.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\">\n\t\t\t\t\t\tIR AHORA\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1f041a elementor-reverse-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1f041a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c23ab7\" data-id=\"6c23ab7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0470b4 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0470b4\" data-element_type=\"section\" data-e-type=\"section\" id=\"our_services\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b677e9d\" data-id=\"b677e9d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73faec4 elementor-widget elementor-widget-image\" data-id=\"73faec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2215\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f6fd53 elementor-widget elementor-widget-heading\" data-id=\"5f6fd53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sobre nuestros servicios de Consultor\u00eda e I+D<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-468d8ad elementor-widget elementor-widget-spacer\" data-id=\"468d8ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de31758 elementor-widget elementor-widget-text-editor\" data-id=\"de31758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mejor transformaci\u00f3n digital es deliberada y razonada, tomando decisiones de inversi\u00f3n y cambios con base en el contexto de la organizaci\u00f3n y las oportunidades que brinda el estado del arte. Sin embargo el contexto y el estado del arte cambian aceleradamente. Cuando su negocio permite el tiempo para irse posicionando tecnol\u00f3gicamente, una combinaci\u00f3n adecuada de consultor\u00eda, desarrollo de pruebas de concepto e investigaci\u00f3n si es necesario, contribuye a disminuir la incertidumbre sobre las decisiones que tomar.<\/p><p>En Centauri tenemos a\u00f1os acumulados solucionando problemas gerenciales y tecnol\u00f3gicos complejos o elaborando y ayudando a implementar estrategias de transformaci\u00f3n digital. Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo.<\/p><p>Nuestro historial de logros incluye transformaciones digitales completas de servicios o negocios, incluyendo conversi\u00f3n a transaccionalidad digital, digitalizaci\u00f3n de operaciones enteras, normativa de comercio electr\u00f3nico, an\u00e1lisis e interpretaci\u00f3n de cuerpos de datos para toma de decisiones, automatizaci\u00f3n de procesos de diagn\u00f3stico, pruebas de concepto de sistemas de informaci\u00f3n completos, diagn\u00f3sticos de fallas de sistemas y dise\u00f1o de arquitecturas avanzadas. Nuestro personal tiene a\u00f1os de experiencia en proyectos sofisticados de Investigaci\u00f3n y Desarrollo al igual que a\u00f1os de experiencia participando en Juntas Directivas, Comit\u00e9s Ejecutivos, Alta Gerencia y Gerencia de Negocios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebc979c all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebc979c\" data-element_type=\"section\" data-e-type=\"section\" id=\"vigilancia\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d0c8911\" data-id=\"d0c8911\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23c09a3 elementor-widget elementor-widget-image\" data-id=\"23c09a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2117\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/computer3-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341c5d8 elementor-widget elementor-widget-heading\" data-id=\"341c5d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vigilancia de Seguridad (SOC 24X7)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-477f90a elementor-widget elementor-widget-spacer\" data-id=\"477f90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39b7569 elementor-widget elementor-widget-text-editor\" data-id=\"39b7569\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los intrusos no descansan, nosotros tampoco. Usando herramientas de punta y personal altamente calificado vigilamos y actuamos de manera permanente para protegerlo. Descanse, nosotros estamos cuidando su negocio.<\/p><p>Operamos nuestro Centro de Vigilancia de Seguridad (SOC, por sus siglas en ingl\u00e9s) con un equipo experimentado en seguridad inform\u00e1tica y con una plataforma de \u00faltima generaci\u00f3n, multifuncional; una combinaci\u00f3n que le permite a nuestros clientes varios niveles de seguridad acordes con sus necesidades de negocios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-770662b all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"770662b\" data-element_type=\"section\" data-e-type=\"section\" id=\"gestion\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-03c910c\" data-id=\"03c910c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ee78ff elementor-widget elementor-widget-image\" data-id=\"8ee78ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2118\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/gestion-de-seguridad3-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd9cb6e elementor-widget elementor-widget-heading\" data-id=\"fd9cb6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gesti\u00f3n de Seguridad <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef8a1b3 elementor-widget elementor-widget-spacer\" data-id=\"ef8a1b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4fde94 elementor-widget elementor-widget-text-editor\" data-id=\"b4fde94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las herramientas son importantes pero operar con ellas en forma correcta lo es mucho m\u00e1s. Nuestro esquema de gesti\u00f3n de seguridad le permitir\u00e1 tener control total sobre la operaci\u00f3n de su infraestructura, su gesti\u00f3n y gobierno. Adem\u00e1s, contar\u00e1 con nuestra ayuda experta para la mejora continua.<\/p><p>Convertimos sus objetivos de seguridad en planes estrat\u00e9gicos que lo ayudar\u00e1n a determinar cu\u00e1les son las inversiones correctas. Apoyamos en establecer m\u00e9tricas de seguridad que permitan determinar el estado de seguridad de la organizaci\u00f3n y sustentar con \u00e9xito, sin ambig\u00fcedades, el cumplimiento de los objetivos de seguridad. Estas m\u00e9tricas tambi\u00e9n facilitan el proceso de maduraci\u00f3n de las capacidades de seguridad de su organizaci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97cfc5f all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97cfc5f\" data-element_type=\"section\" data-e-type=\"section\" id=\"analisis-de-riesgo\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-135dcec\" data-id=\"135dcec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d961eeb elementor-widget elementor-widget-image\" data-id=\"d961eeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2119\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8373ae9 elementor-widget elementor-widget-heading\" data-id=\"8373ae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An\u00e1lisis de Riesgos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23e814f elementor-widget elementor-widget-spacer\" data-id=\"23e814f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e59f39 elementor-widget elementor-widget-text-editor\" data-id=\"6e59f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La desconexi\u00f3n entre las inversiones de seguridad y el riesgo real es un fallo grave com\u00fan. En seguridad todo se debe asegurar en funci\u00f3n de la evaluaci\u00f3n del riesgo, mientras m\u00e1s pensado, argumentado y ponderado, mejor.<\/p><p>Identificamos los riesgos principales y sus impactos con base en sus objetivos de negocio.<\/p><p>Le damos herramientas que le permitan gestionar sus riesgos y dise\u00f1amos controles de seguridad para disminuir el impacto ajust\u00e1ndonos a las necesidades y a los recursos de su organizaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a9f8187 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9f8187\" data-element_type=\"section\" data-e-type=\"section\" id=\"pentest\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d0950f1\" data-id=\"d0950f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5777145 elementor-widget elementor-widget-image\" data-id=\"5777145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2120\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/pentes1-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-347b7d6 elementor-widget elementor-widget-heading\" data-id=\"347b7d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pentest<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d772816 elementor-widget elementor-widget-spacer\" data-id=\"d772816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda90e3 elementor-widget elementor-widget-text-editor\" data-id=\"fda90e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Compruebe cu\u00e1n resistentes son sus defensas a un ataque. Usando conocimientos especializados nuestro equipo realizar\u00e1 una simulaci\u00f3n de ataque y descubrir\u00e1 c\u00f3mo un atacante podr\u00eda penetrar e impactar su plataforma de informaci\u00f3n.<\/p><p>Nuestro equipo de \u00abEthical Hackers\u00bb, certificados y experimentados, probar\u00e1n sus defensas con intentos creativos de intrusi\u00f3n, pero coordinando con el personal m\u00ednimo con necesidad-de-saber.<\/p><p>Cuando se combina con nuestro servicio Cyberguard de vigilancia SOC, el servicio de pruebas de intrusi\u00f3n tambi\u00e9n permite validar la efectividad de herramientas de detecci\u00f3n de anomal\u00edas de la organizaci\u00f3n sin necesidad de instalar puertas traseras que contaminar\u00edan los sistemas inform\u00e1ticos; es decir el servicio combinado emula actividades del crimen organizado sin causar da\u00f1o.<\/p><p>Solicite nuestro servicio de pruebas de intrusi\u00f3n con aprendizaje de m\u00e1quina (machine learning) y d\u00e9jese sorprender por la relaci\u00f3n costo-beneficio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c365087 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c365087\" data-element_type=\"section\" data-e-type=\"section\" id=\"respuesta-a-incidente\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b248aae\" data-id=\"b248aae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-befa7d9 elementor-widget elementor-widget-image\" data-id=\"befa7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2119\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/forense2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d86d88 elementor-widget elementor-widget-heading\" data-id=\"4d86d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Respuesta a Incidente y An\u00e1lisis Forense<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27d6c5a elementor-widget elementor-widget-spacer\" data-id=\"27d6c5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2220229 elementor-widget elementor-widget-text-editor\" data-id=\"2220229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ha ocurrido un incidente de seguridad. \u00bfC\u00f3mo responder? \u00bfC\u00f3mo inici\u00f3 todo? \u00bfQu\u00e9 sistemas fueron afectados? \u00bfC\u00f3mo preservar las evidencias? \u00bf C\u00f3mo responder a los entes reguladores?<\/p><p>Tenemos un equipo de expertos con experiencia pr\u00e1ctica de campo y con alta calificaci\u00f3n acad\u00e9mica. Hemos vivido muchas veces el fragor de descubrir a un atacante, encontrar sus huellas, analizar sus acciones, neutralizarlo, reducir su impacto y apoyar a la organizaci\u00f3n en el manejo de la comunicaci\u00f3n p\u00fablica.<\/p><p>Usando herramientas sofisticadas, vamos a la caza del agresor m\u00e1s all\u00e1 de lo obvio. Recopilamos evidencias siguiendo m\u00e9todos que permitan cumplir con los requisitos forenses legales y le damos un informe detallado, en un lenguaje t\u00e9cnico y gerencial de lo que ha ocurrido y c\u00f3mo evitar su repetici\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9dc0d96 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dc0d96\" data-element_type=\"section\" data-e-type=\"section\" id=\"continuidad\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-74147c9\" data-id=\"74147c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f861d6 elementor-widget elementor-widget-image\" data-id=\"5f861d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2128\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/continuidad-de-negocio2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a9ef0a elementor-widget elementor-widget-heading\" data-id=\"7a9ef0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Continuidad de Negocios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bd33eb elementor-widget elementor-widget-spacer\" data-id=\"7bd33eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff4e85f elementor-widget elementor-widget-text-editor\" data-id=\"ff4e85f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No lo deje a la suerte. Le ayudamos a construir y probar sus planes para que llegado el momento el impacto sea manejable y todo se recupere eficaz y r\u00e1pidamente<\/p><p>Identificamos desastres potenciales que pudieran poner en riesgo la prestaci\u00f3n de sus servicios, incluyendo fallas de sistemas y desastres naturales, y c\u00f3mo afectar\u00edan espec\u00edficamente en su negocio. Esto permite debatir su tolerancia al riesgo y dise\u00f1ar planes que preparen a su organizaci\u00f3n para sobrevivir un impacto y poder retornar a la normalidad lo antes posible.<\/p><p>Tambi\u00e9n entrenamos a su personal para afrontar eventos de este tipo con el fin de disminuir el impacto en la medida de lo posible y disminuir el tiempo de retorno a la normalidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7786a3b all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7786a3b\" data-element_type=\"section\" data-e-type=\"section\" id=\"seguridad-de-codigo\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-286d6b0\" data-id=\"286d6b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-944d059 elementor-widget elementor-widget-image\" data-id=\"944d059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2129\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/compu3-1-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e94af8a elementor-widget elementor-widget-heading\" data-id=\"e94af8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revisi\u00f3n o Dise\u00f1o de Seguridad de C\u00f3digo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5a974 elementor-widget elementor-widget-spacer\" data-id=\"dc5a974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f72ea elementor-widget elementor-widget-text-editor\" data-id=\"64f72ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Revisamos su software para descubrir errores de seguridad, vulnerabilidades, artilugios para cometer fraude y otras amenazas. Si prefiere, participamos en el dise\u00f1o de seguridad del software desde el inicio, para evitarle contratiempos.<\/p><p>Prevemos riesgos potenciales de seguridad en sus sistemas desde el momento de la conceptualizaci\u00f3n hasta la implementaci\u00f3n, mediante el uso de medidas de seguridad que forman parte de los requerimientos del software, revisiones del c\u00f3digo desarrollado antes de implementarlo y de las pruebas en la arquitectura donde ser\u00e1 implementado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d32527f all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d32527f\" data-element_type=\"section\" data-e-type=\"section\" id=\"seguridad-para-teletrabajo\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ad7e78\" data-id=\"5ad7e78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8ec564 elementor-widget elementor-widget-image\" data-id=\"a8ec564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2130\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/teletrabajo2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-241111a elementor-widget elementor-widget-heading\" data-id=\"241111a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revisi\u00f3n de Seguridad para Teletrabajo (911 Seguridad)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a76c4e5 elementor-widget elementor-widget-spacer\" data-id=\"a76c4e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f155a3 elementor-widget elementor-widget-text-editor\" data-id=\"9f155a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfEst\u00e1n sus tele-colaboradores tan protegidos como cu\u00e1ndo estaban en la red corporativa? Perm\u00edtanos revisar sus equipos, sus defensas, los protocolos de conexi\u00f3n y evaluar el riesgo para su organizaci\u00f3n.<\/p><p>El cambio a teletrabajo fue una buena idea pero hubo muy poco tiempo. Revisamos si quedaron cabos sueltos que puedan resultar costosos o afectar su imagen. Verificamos mecanismos de autenticaci\u00f3n, conexiones seguras, respaldos, protecci\u00f3n de datos y mitigaci\u00f3n de riesgos en conjunto con su personal. Como opci\u00f3n, agregamos vigilancia SOC por 3 meses.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0af2843 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0af2843\" data-element_type=\"section\" data-e-type=\"section\" id=\"infraestructura\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-58bac9a\" data-id=\"58bac9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f900535 elementor-widget elementor-widget-image\" data-id=\"f900535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2121\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/infraestructura2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-526235e elementor-widget elementor-widget-heading\" data-id=\"526235e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dise\u00f1os de Infraestructura y Arquitectura de Seguridad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed1e388 elementor-widget elementor-widget-spacer\" data-id=\"ed1e388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5a9da1 elementor-widget elementor-widget-text-editor\" data-id=\"b5a9da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La efectividad de los controles no es la suma de sus ventajas y funciones individuales. El dise\u00f1o adecuado y consciente de la arquitectura es un elemento cr\u00edtico.<\/p><p>Nuestro personal combina conocimiento acad\u00e9mico con experiencia de batalla, en entornos de misi\u00f3n cr\u00edtica nacionales e internacionales. Esto nos permite dise\u00f1ar arquitecturas y plataformas de seguridad que balanceen controles digitales eficaces, vigilancia efectiva, funcionalidad fluida para el usuario y gobernanza clara.<\/p><p>Nuestro personal forma arquitectos de soluciones tecnol\u00f3gicas en universidades principales de Panam\u00e1 y otros pa\u00edses. Nuestra red de contactos internacionales nos permite conocer el estado del arte de la industria y adaptarlo a su entorno.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dc90005 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc90005\" data-element_type=\"section\" data-e-type=\"section\" id=\"politicas\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ec09417\" data-id=\"ec09417\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8a7fd1 elementor-widget elementor-widget-image\" data-id=\"b8a7fd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2122\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/politica-de-seguridad2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d63f210 elementor-widget elementor-widget-heading\" data-id=\"d63f210\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edticas de Seguridad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf69873 elementor-widget elementor-widget-spacer\" data-id=\"bf69873\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf31ef elementor-widget elementor-widget-text-editor\" data-id=\"2bf31ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La intuici\u00f3n y el talento son importantes pero no suficientes. Construimos o evaluamos sus pol\u00edticas de seguridad para asegurar que son completas, sin dejar flancos d\u00e9biles o zonas grises, pero razonables para la idiosincracia de su organizaci\u00f3n.<\/p><p>Sea una organizaci\u00f3n consecuente con sus pol\u00edticas, traduzca sus estrategias de defensa digital en hechos.<\/p><p>Sus pol\u00edticas se quedan en el papel? Tratamos las pol\u00edticas de seguridad como un proceso de formaci\u00f3n de h\u00e1bitos.<\/p><p>Dise\u00f1amos pol\u00edticas basadas en los objetivos y riesgos de su negocio, tomando en cuenta la idiosincrasia de su organizaci\u00f3n.<\/p><p>Recomendamos la mejor forma de madurar las pol\u00edticas y c\u00f3mo medir el progreso.<\/p><p>Al combinar este servicio con nuestro servicio de gesti\u00f3n de seguridad usted puede medir a trav\u00e9s de un tablero de control la efectividad de sus pol\u00edticas. Transforme su empresa de reactiva a proactiva en seguridad en poco tiempo. El secreto radica en el cambio de h\u00e1bitos, perm\u00edtanos apoyarlo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a8e9e59 all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8e9e59\" data-element_type=\"section\" data-e-type=\"section\" id=\"auditoria\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c6bd5c4\" data-id=\"c6bd5c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6547961 elementor-widget elementor-widget-image\" data-id=\"6547961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2123\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/brecha2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baa7023 elementor-widget elementor-widget-heading\" data-id=\"baa7023\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revisi\u00f3n de Brechas de Seguridad y Auditor\u00eda de Sistemas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e05aa47 elementor-widget elementor-widget-spacer\" data-id=\"e05aa47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fab5db4 elementor-widget elementor-widget-text-editor\" data-id=\"fab5db4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Revisamos su arquitectura contra los est\u00e1ndares de la industria y le indicamos como cumplir.<\/p><p>Diagnostique con rayos X. Nuestro servicio de an\u00e1lisis de brecha le permite evaluar en forma m\u00e1s profunda su postura de seguridad contra las mejores pr\u00e1cticas de la industria.<\/p><p>Al igual que la habilidad de un m\u00e9dico hace la diferencia, nuestros especialistas est\u00e1n catalogados entre los mejores de la regi\u00f3n por lo que puede esperar mejores resultados. Para el servicio combinamos herramientas poderosas de revisi\u00f3n de sistemas con sesiones estrat\u00e9gicas de evaluaci\u00f3n junto con el equipo de la organizaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bbb347d all-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbb347d\" data-element_type=\"section\" data-e-type=\"section\" id=\"formacion\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-da0cf39\" data-id=\"da0cf39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-241cb88 elementor-widget elementor-widget-image\" data-id=\"241cb88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"517\" src=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1-1024x662.jpg\" class=\"attachment-large size-large wp-image-2124\" alt=\"\" srcset=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1-1024x662.jpg 1024w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1-300x194.jpg 300w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1-768x496.jpg 768w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1-600x388.jpg 600w, https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/capacitacion2-1.jpg 1222w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26fbffb elementor-widget elementor-widget-heading\" data-id=\"26fbffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n y Capacitaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09359e1 elementor-widget elementor-widget-spacer\" data-id=\"09359e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-749bc6b elementor-widget elementor-widget-text-editor\" data-id=\"749bc6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cursos y asesor\u00eda en aprendizaje independiente a la medida para personal t\u00e9cnico, gerencial y altos ejecutivos. Dictados por expertos con alta formaci\u00f3n y experiencia, especialistas en el campo, investigadores y profesores universitarios.<\/p><p>El conocimiento experto de sus colaboradores es la primera y m\u00e1s importante l\u00ednea de defensa. Poco vale invertir en tecnolog\u00eda si no hay quien la comprenda y aproveche. Podemos ayudarle. Tenemos especialistas con grados de Ph.D. y Maestr\u00eda en el ramo, calificados y frecuentemente activos como profesores universitarios. Tienen experiencia real de primer nivel (CEO, CIO, CISO).<\/p><p>Dise\u00f1amos cursos a la medida de su industria y de sus necesidades. Con nosotros no solo aprender\u00e1 el c\u00f3mo sino el por qu\u00e9.<\/p><p>Cursos en las \u00e1reas de:<\/p><ul class=\"list-form-capacitac\"><li>Seguridad de la informaci\u00f3n.<\/li><li>An\u00e1lisis forense.<\/li><li>Gesti\u00f3n de la seguridad.<\/li><li>T\u00e9cnicas criptogr\u00e1ficas.<\/li><li>Seguridad para directivos y altos gerentes.<\/li><\/ul><p>Nuestros cursos pueden incluir evaluaciones y emitir certificados de resultados satisfactorios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-68018b9 elementor-widget elementor-widget-spacer\" data-id=\"68018b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d73454c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d73454c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Comparte en: <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b17a634 elementor-share-buttons--view-icon elementor-share-buttons--shape-circle elementor-share-buttons--color-custom elementor-widget__width-initial elementor-share-buttons--skin-gradient elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"b17a634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-telegram\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48295ca elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48295ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a83520\" data-id=\"4a83520\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62545ad elementor-widget elementor-widget-heading\" data-id=\"62545ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Inf\u00f3rmate con Nosotros<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed5cf1b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ed5cf1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4de56f8 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"4de56f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/Infografia.webp);\" role=\"img\" aria-label=\"Infografia\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tVISITA NUESTRO CTN\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tConoce las \u00faltimas noticias acerca de la ciberseguridad\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/centauritech.com\/en\/recursos-centauri\/\">\n\t\t\t\t\t\tIR AHORA\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-ribbon elementor-ribbon-right\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\t\u00a1Infograf\u00edas!\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55707d8 elementor-widget elementor-widget-spacer\" data-id=\"55707d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d7dc7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d7dc7f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6bf6fa0\" data-id=\"6bf6fa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dedb90 elementor-widget elementor-widget-heading\" data-id=\"8dedb90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9janos tus datos para contratar nuestros servicios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13e228b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"13e228b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46816eb elementor-widget elementor-widget-text-editor\" data-id=\"46816eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEn el mundo digital actual, la ciberseguridad es esencial. Comencemos a trabajar juntos para proteger su empresa de amenazas cibern\u00e9ticas y mantener su informaci\u00f3n segura. Conf\u00ede en nuestra experiencia y conocimientos para fortalecer su seguridad\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bd16414\" data-id=\"bd16414\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d531e3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5d531e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/centauritech.com\/en\/contactenos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ir Ahora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo Solicitar Demo Sobre nuestros servicios de Consultor\u00eda e I + D La mejor transformaci\u00f3n digital es deliberada y razonada, tomando decisiones de inversi\u00f3n y cambios con base en el contexto de la organizaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2213","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consultor\u00eda E I+D - Centauri Technologies Corporation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centauritech.com\/en\/consultoria-e-id\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consultor\u00eda E I+D - Centauri Technologies Corporation\" \/>\n<meta property=\"og:description\" content=\"Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo Solicitar Demo Sobre nuestros servicios de Consultor\u00eda e I + D La mejor transformaci\u00f3n digital es deliberada y razonada, tomando decisiones de inversi\u00f3n y cambios con base en el contexto de la organizaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centauritech.com\/en\/consultoria-e-id\/\" \/>\n<meta property=\"og:site_name\" content=\"Centauri Technologies Corporation\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T21:39:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1222\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/\",\"url\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/\",\"name\":\"Consultor\u00eda E I+D - Centauri Technologies Corporation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centauritech.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/consultoria2-1-1024x662.jpg\",\"datePublished\":\"2022-08-18T22:51:59+00:00\",\"dateModified\":\"2025-10-01T21:39:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centauritech.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/consultoria2-1-1024x662.jpg\",\"contentUrl\":\"https:\\\/\\\/centauritech.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/consultoria2-1-1024x662.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/consultoria-e-id\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centauritech.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consultor\u00eda E I+D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/#website\",\"url\":\"https:\\\/\\\/centauritech.com\\\/\",\"name\":\"Centauri Technologies Corporation\",\"description\":\"Somos su brazo de innovaci\u00f3n en tecnolog\u00eda de la informaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centauritech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/#organization\",\"name\":\"Centauri Technologies Corporation\",\"url\":\"https:\\\/\\\/centauritech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/centauritech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centauritech.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-centauri.png\",\"contentUrl\":\"https:\\\/\\\/centauritech.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-centauri.png\",\"width\":351,\"height\":201,\"caption\":\"Centauri Technologies Corporation\"},\"image\":{\"@id\":\"https:\\\/\\\/centauritech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consultor\u00eda E I+D - Centauri Technologies Corporation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centauritech.com\/en\/consultoria-e-id\/","og_locale":"en_US","og_type":"article","og_title":"Consultor\u00eda E I+D - Centauri Technologies Corporation","og_description":"Combinamos experiencia ejecutiva, logros de ingenier\u00eda, alta formaci\u00f3n acad\u00e9mica e historial en I+D para posicionar tecnol\u00f3gicamente su negocio y hacerlo m\u00e1s competitivo Solicitar Demo Sobre nuestros servicios de Consultor\u00eda e I + D La mejor transformaci\u00f3n digital es deliberada y razonada, tomando decisiones de inversi\u00f3n y cambios con base en el contexto de la organizaci\u00f3n [&hellip;]","og_url":"https:\/\/centauritech.com\/en\/consultoria-e-id\/","og_site_name":"Centauri Technologies Corporation","article_modified_time":"2025-10-01T21:39:08+00:00","og_image":[{"width":1222,"height":790,"url":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/centauritech.com\/consultoria-e-id\/","url":"https:\/\/centauritech.com\/consultoria-e-id\/","name":"Consultor\u00eda E I+D - Centauri Technologies Corporation","isPartOf":{"@id":"https:\/\/centauritech.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centauritech.com\/consultoria-e-id\/#primaryimage"},"image":{"@id":"https:\/\/centauritech.com\/consultoria-e-id\/#primaryimage"},"thumbnailUrl":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg","datePublished":"2022-08-18T22:51:59+00:00","dateModified":"2025-10-01T21:39:08+00:00","breadcrumb":{"@id":"https:\/\/centauritech.com\/consultoria-e-id\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centauritech.com\/consultoria-e-id\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centauritech.com\/consultoria-e-id\/#primaryimage","url":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg","contentUrl":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/08\/consultoria2-1-1024x662.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/centauritech.com\/consultoria-e-id\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centauritech.com\/"},{"@type":"ListItem","position":2,"name":"Consultor\u00eda E I+D"}]},{"@type":"WebSite","@id":"https:\/\/centauritech.com\/#website","url":"https:\/\/centauritech.com\/","name":"Centauri Technologies Corporation","description":"Somos su brazo de innovaci\u00f3n en tecnolog\u00eda de la informaci\u00f3n","publisher":{"@id":"https:\/\/centauritech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centauritech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/centauritech.com\/#organization","name":"Centauri Technologies Corporation","url":"https:\/\/centauritech.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/centauritech.com\/#\/schema\/logo\/image\/","url":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/05\/logo-centauri.png","contentUrl":"https:\/\/centauritech.com\/wp-content\/uploads\/2022\/05\/logo-centauri.png","width":351,"height":201,"caption":"Centauri Technologies Corporation"},"image":{"@id":"https:\/\/centauritech.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/pages\/2213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/comments?post=2213"}],"version-history":[{"count":80,"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/pages\/2213\/revisions"}],"predecessor-version":[{"id":4802,"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/pages\/2213\/revisions\/4802"}],"wp:attachment":[{"href":"https:\/\/centauritech.com\/en\/wp-json\/wp\/v2\/media?parent=2213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}